{"id":17578,"date":"2026-05-11T09:30:00","date_gmt":"2026-05-11T07:30:00","guid":{"rendered":"https:\/\/www.umanitaria.it\/milano\/?p=17578"},"modified":"2026-04-27T15:20:29","modified_gmt":"2026-04-27T13:20:29","slug":"prenota-ora-il-tuo-appuntamento-2","status":"publish","type":"post","link":"https:\/\/www.umanitaria.it\/milano\/corsi-humaniter\/prenota-ora-il-tuo-appuntamento-2\/","title":{"rendered":"Prenota ora il tuo appuntamento"},"content":{"rendered":"\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/societa-umanitaria.reservio.com\" target=\"_blank\" rel=\"noreferrer noopener\">PRENOTA IL TUO APPUNTAMENTO<\/a><\/div>\n<\/div>\n\n\n\n<p>Da gioved\u00ec&nbsp;<strong>28 maggio alle 18.30&nbsp;<\/strong>sar\u00e0 disponibile in Segreteria e online il nuovo palinsesto dei corsi per l\u2019anno scolastico 2026\/27.<\/p>\n\n\n\n<p>Dall\u2019<strong>11 maggio<\/strong>&nbsp;<strong>alle 9.30<\/strong>&nbsp;sar\u00e0 possibile prendere l\u2019appuntamento per le iscrizioni.<\/p>\n\n\n\n<p>Pu\u00f2 prenotare il suo appuntamento online <strong><a href=\"https:\/\/societa-umanitaria.reservio.com\" target=\"_blank\" rel=\"noreferrer noopener\">cliccando qui<\/a> <\/strong>o in alternativa pu\u00f2 chiamare lo 02\/55192966 \u2013 02\/57968331 \u2013 02\/57968333<strong>&nbsp;dal luned\u00ec al gioved\u00ec dalle 9.30 alle 12.45 e dalle 14.00 alle 17.00, il venerd\u00ec dalle 9.30 alle 12.45.<\/strong> Potr\u00e0 anche prendere l\u2019appuntamento di persona sempre rispettando gli orari sopra indicati.<\/p>\n\n\n\n<p>Ogni appuntamento d\u00e0 diritto ad una sola iscrizione, pertanto se ci si deve iscrivere con un\u2019altra persona sar\u00e0 necessario prendere due appuntamenti.<br>Le richieste di appuntamento via mail non verranno prese in considerazione.<\/p>\n\n\n\n<p>Le&nbsp;iscrizioni partiranno da&nbsp;<strong>luned\u00ec 8 giugno 2026 alle ore 9.00 sia in presenza che online.<\/strong><\/p>\n\n\n\n<p>Chi non dovesse presentarsi nel giorno e nell\u2019ora stabilita dall\u2019appuntamento, dovr\u00e0 fissarne uno nuovo. Se nel frattempo dovesse cambiare idea o si iscrivesse online dovr\u00e0 informare la Segreteria annullando il suo appuntamento.<br>Il giorno dell\u2019appuntamento ci si dovr\u00e0 presentare in Segreteria nell\u2019ora stabilita con il numero&nbsp;<strong>dei codici estrapolati dal programma dei corsi&nbsp;2026\/27.<\/strong><\/p>\n\n\n\n<p>Qualora dovesse decidere di iscriversi online direttamente dall\u2019<strong>8 giugno<\/strong>, la informo che da quest\u2019anno ci sar\u00e0 un nuovo programma che render\u00e0 pi\u00f9 semplice la procedura di iscrizione. <strong>Le credenziali utilizzate fino ad ora NON saranno pi\u00f9 valide, le nuove saranno inviate via mail entro la data di inizio delle iscrizioni.<\/strong><\/p>\n\n\n\n<p>Le quote di iscrizione per il prossimo&nbsp;anno sono le seguenti:<\/p>\n\n\n\n<p><strong>RINNOVI<\/strong><\/p>\n\n\n\n<p><strong>Quota di iscrizione alla Societ\u00e0 Umanitaria \u20ac 10,00 da aggiungere alla formula scelta<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>FORMULA A&nbsp;\/&nbsp;<\/strong>2 corsi in presenza + 1 online&nbsp;<em>\u20ac 130,00<\/em><\/li>\n\n\n\n<li><strong>FORMULA B&nbsp;\/&nbsp;<\/strong>3 corsi in presenza + 2 online&nbsp;<em>\u20ac 190,00<\/em><\/li>\n\n\n\n<li><strong>FORMULA C&nbsp;\/&nbsp;<\/strong>4 corsi online&nbsp;<em>\u20ac 150,00<\/em><\/li>\n<\/ul>\n\n\n\n<p>La quota comprende l\u2019ingresso alla Stagione Concerti 2026\/27 e l\u2019iscrizione gratuita al Workshop di Archeologia<\/p>\n\n\n\n<p><strong>NUOVI SOCI<\/strong><\/p>\n\n\n\n<p><strong>Quota di iscrizione alla Societ\u00e0 Umanitaria \u20ac 10,00 da aggiungere alla formula scelta<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>FORMULA A&nbsp;\/&nbsp;<\/strong>2 corsi in presenza + 1 online&nbsp;<em>\u20ac 150,00<\/em><\/li>\n\n\n\n<li><strong>FORMULA B&nbsp;\/&nbsp;<\/strong>3 corsi in presenza + 2 online&nbsp;<em>\u20ac 220,00<\/em><\/li>\n\n\n\n<li><strong>FORMULA C&nbsp;\/&nbsp;<\/strong>4 corsi online&nbsp;<em>\u20ac 150,00<\/em><\/li>\n<\/ul>\n\n\n\n<p>La quota comprende l\u2019ingresso alla Stagione Concerti 2026\/27 e l\u2019iscrizione gratuita al Workshop di Archeologia<\/p>\n\n\n\n<p>Su richiesta sar\u00e0 possibile integrare il numero dei corsi versando la quota aggiuntiva di \u20ac 70,00 per i rinnovi, \u20ac 80,00 per i nuovi iscritti e \u20ac 30,00 per i corsi online.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da gioved\u00ec&nbsp;28 maggio alle 18.30&nbsp;sar\u00e0 disponibile in Segreteria e online il nuovo palinsesto dei corsi per l\u2019anno scolastico 2026\/27. Dall\u201911 maggio&nbsp;alle 9.30&nbsp;sar\u00e0 possibile prendere l\u2019appuntamento per le iscrizioni. Pu\u00f2 prenotare il suo appuntamento online cliccando qui o in alternativa pu\u00f2 chiamare lo 02\/55192966 \u2013 02\/57968331 \u2013 02\/57968333&nbsp;dal luned\u00ec al gioved\u00ec dalle 9.30 alle 12.45 e &#8230; <a title=\"Prenota ora il tuo appuntamento\" class=\"read-more\" href=\"https:\/\/www.umanitaria.it\/milano\/corsi-humaniter\/prenota-ora-il-tuo-appuntamento-2\/\" aria-label=\"Per saperne di pi\u00f9 su Prenota ora il tuo appuntamento\">Leggi tutto<\/a><\/p>\n","protected":false},"author":5,"featured_media":17575,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"footnotes":""},"categories":[140],"tags":[],"class_list":["post-17578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corsi-humaniter"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.umanitaria.it\/milano\/wp-json\/wp\/v2\/posts\/17578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.umanitaria.it\/milano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.umanitaria.it\/milano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.umanitaria.it\/milano\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.umanitaria.it\/milano\/wp-json\/wp\/v2\/comments?post=17578"}],"version-history":[{"count":1,"href":"https:\/\/www.umanitaria.it\/milano\/wp-json\/wp\/v2\/posts\/17578\/revisions"}],"predecessor-version":[{"id":17582,"href":"https:\/\/www.umanitaria.it\/milano\/wp-json\/wp\/v2\/posts\/17578\/revisions\/17582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.umanitaria.it\/milano\/wp-json\/wp\/v2\/media\/17575"}],"wp:attachment":[{"href":"https:\/\/www.umanitaria.it\/milano\/wp-json\/wp\/v2\/media?parent=17578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.umanitaria.it\/milano\/wp-json\/wp\/v2\/categories?post=17578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.umanitaria.it\/milano\/wp-json\/wp\/v2\/tags?post=17578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}